{"id":71,"date":"2023-03-26T17:00:26","date_gmt":"2023-03-26T16:00:26","guid":{"rendered":"https:\/\/savibas.com\/?page_id=71"},"modified":"2023-04-09T09:19:58","modified_gmt":"2023-04-09T08:19:58","slug":"contact-us","status":"publish","type":"page","link":"https:\/\/savibas.com\/index.php\/contact-us\/","title":{"rendered":"Contact Us"},"content":{"rendered":"<div class=\"wpforms-container wpforms-container-full wpforms-block wpforms-block-909675ea-d26c-473b-9b70-5c336c017e7a\" id=\"wpforms-93\"><form id=\"wpforms-form-93\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"93\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/index.php\/wp-json\/wp\/v2\/pages\/71\" data-token=\"3adf9a6887b152bbbcde9e965c9d8921\"><noscript class=\"wpforms-error-noscript\">Please enable JavaScript in your browser to complete this form.<\/noscript><div class=\"wpforms-field-container\"><div id=\"wpforms-93-field_0-container\" class=\"wpforms-field wpforms-field-name\" data-field-id=\"0\"><label class=\"wpforms-field-label\" for=\"wpforms-93-field_0\">Name <span class=\"wpforms-required-label\">*<\/span><\/label><div class=\"wpforms-field-row wpforms-field-medium\"><div class=\"wpforms-field-row-block wpforms-first wpforms-one-half\"><input type=\"text\" id=\"wpforms-93-field_0\" class=\"wpforms-field-name-first wpforms-field-required\" name=\"wpforms[fields][0][first]\" required><label for=\"wpforms-93-field_0\" class=\"wpforms-field-sublabel after \">First<\/label><\/div><div class=\"wpforms-field-row-block wpforms-one-half\"><input type=\"text\" id=\"wpforms-93-field_0-last\" class=\"wpforms-field-name-last wpforms-field-required\" name=\"wpforms[fields][0][last]\" required><label for=\"wpforms-93-field_0-last\" class=\"wpforms-field-sublabel after \">Last<\/label><\/div><\/div><\/div><div id=\"wpforms-93-field_1-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"1\"><label class=\"wpforms-field-label\" for=\"wpforms-93-field_1\">Email <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"email\" id=\"wpforms-93-field_1\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][1]\" placeholder=\"sample@abc.com\" spellcheck=\"false\" required><\/div><div id=\"wpforms-93-field_2-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"2\"><label class=\"wpforms-field-label\" for=\"wpforms-93-field_2\">Message - Please Explain Your Querry or Feedback here!<\/label><textarea id=\"wpforms-93-field_2\" class=\"wpforms-field-medium\" name=\"wpforms[fields][2]\" ><\/textarea><\/div><\/div><!-- .wpforms-field-container --><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"93\"><input type=\"hidden\" name=\"wpforms[author]\" value=\"2\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-93\" class=\"wpforms-submit\" data-alt-text=\"Sending\u2026\" data-submit-text=\"Submit\" aria-live=\"assertive\" value=\"wpforms-submit\">Submit<\/button><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/savibas.com\/wp-content\/plugins\/wpforms-lite\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"Loading\"><\/div><\/form><\/div>  <!-- .wpforms-container -->","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-71","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/savibas.com\/index.php\/wp-json\/wp\/v2\/pages\/71","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/savibas.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/savibas.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/savibas.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/savibas.com\/index.php\/wp-json\/wp\/v2\/comments?post=71"}],"version-history":[{"count":3,"href":"https:\/\/savibas.com\/index.php\/wp-json\/wp\/v2\/pages\/71\/revisions"}],"predecessor-version":[{"id":330,"href":"https:\/\/savibas.com\/index.php\/wp-json\/wp\/v2\/pages\/71\/revisions\/330"}],"wp:attachment":[{"href":"https:\/\/savibas.com\/index.php\/wp-json\/wp\/v2\/media?parent=71"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}